{"id":950,"date":"2022-11-30T11:50:00","date_gmt":"2022-11-30T14:50:00","guid":{"rendered":"https:\/\/www.ehcomunicacao.com.br\/?p=950"},"modified":"2022-12-26T11:52:46","modified_gmt":"2022-12-26T14:52:46","slug":"cdl-realiza-campanha-natal-presente-2","status":"publish","type":"post","link":"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/11\/30\/cdl-realiza-campanha-natal-presente-2\/","title":{"rendered":"CDL realiza campanha Natal Presente"},"content":{"rendered":"\n<p>A CDL Petr\u00f3polis lan\u00e7ou, no \u00faltimo dia quatro, sua campanha de Natal com o objetivo de incentivar o petropolitano a comprar no com\u00e9rcio local e, assim, fomentar a economia da cidade. Contando com a participa\u00e7\u00e3o da <em>influencer<\/em> <em>digital<\/em>, Amanda Leontina, a publicidade tem como tema Natal Presente, a qual revela que muito mais do que dar um presente para as pessoas queridas, tamb\u00e9m precisamos estar presente, seja com a fam\u00edlia, com os amigos ou na sua pr\u00f3pria cidade.<\/p>\n\n\n\n<p>\u2013 Nossa campanha desperta no petropolitano o sentimento de pertencimento \u00e0 cidade e de participa\u00e7\u00e3o em seu crescimento e desenvolvimento. Estar presente no com\u00e9rcio local \u00e9 fazer com que sua cidade gere empregos, renda e oportunidades. \u00c9 exatamente isso que queremos e o que nossa cidade precisa neste momento \u2013 revelou o presidente da CDL Petr\u00f3polis, Cl\u00e1udio Mohammad.<\/p>\n\n\n\n<p>Entre as pe\u00e7as de divulga\u00e7\u00e3o da campanha, que conta com o apoio da Sicoob CrediRochas, est\u00e1 um v\u00eddeo institucional patrocinado nas redes sociais, <em>cards<\/em> para as redes sociais e whatsapp, an\u00fancios na Tribuna de Petr\u00f3polis e Di\u00e1rio de Petr\u00f3polis, al\u00e9m de banner no site oficial da CDL Petr\u00f3polis.<\/p>\n\n\n\n<p>A divulga\u00e7\u00e3o do material vai at\u00e9 o 25 de dezembro, Dia de Natal e o v\u00eddeo institucional pode ser acessado no Canal da CDL no YouTube:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Natal Presente - CDL Petr\u00f3polis 2022\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/fwMou11EaRI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A CDL Petr\u00f3polis lan\u00e7ou, no \u00faltimo dia quatro, sua campanha de Natal com o objetivo de incentivar o petropolitano a comprar no com\u00e9rcio local e, assim, fomentar a economia da cidade. Contando com a participa\u00e7\u00e3o da influencer digital, Amanda Leontina, a publicidade tem como tema Natal Presente, a qual revela que muito mais do que dar um presente para as pessoas queridas, tamb\u00e9m precisamos estar presente, seja com a fam\u00edlia, com os amigos ou na sua pr\u00f3pria cidade.<\/p>\n","protected":false},"author":1,"featured_media":947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-releases-clientes"],"_links":{"self":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":2,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"predecessor-version":[{"id":952,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/950\/revisions\/952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/media\/947"}],"wp:attachment":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}