{"id":643,"date":"2017-01-02T08:28:52","date_gmt":"2017-01-02T08:28:52","guid":{"rendered":"https:\/\/demo.themegrill.com\/flash-default-2\/?page_id=5"},"modified":"2025-10-29T16:07:54","modified_gmt":"2025-10-29T19:07:54","slug":"home","status":"publish","type":"page","link":"https:\/\/www.ehcomunicacao.com.br\/","title":{"rendered":"Home"},"content":{"rendered":"<div id=\"pl-643\"  class=\"panel-layout\" ><div id=\"pg-643-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-643-0\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-643-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-0-0-0\" class=\"so-panel widget widget_themegrill_flash_slider tg-section tg-slider-widget panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"tg-slider-widget slider-dark slider-content-left slider-control-center full-width\">\n\t<div class=\"swiper-container\">\n\t\t<div class=\"swiper-wrapper\">\n\t\t\t\n\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slider-image\" >\n\t\t\t\t\t\t\t<img width=\"1920\" height=\"700\"\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/banner-principal4.jpg\"\n\t\t\t\t\t\t\t\t\talt=\"Elabora\u00e7\u00e3o e Gest\u00e3o de Projetos\"\n\t\t\t\t\t\t\t\t\ttitle=\"Elabora\u00e7\u00e3o e Gest\u00e3o de Projetos\"\/>\n\t\t\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slider-content\">\n\t\t\t\t\t\t\t<div class=\"tg-container\">\n\t\t\t\t\t\t\t\t<div class=\"caption-title\">Elabora\u00e7\u00e3o e Gest\u00e3o de Projetos<\/div>\n\t\t\t\t\t\t\t\t<div class=\"caption-desc\">Empresas e pessoas f\u00edsicas que pensam em tirar projetos do campo das ideias e fazer acontecer, buscam meios de execu\u00e7\u00e3o como leis de incentivo e outros programas de fomentos. Somos especializados na elabora\u00e7\u00e3o de projetos e gest\u00e3o da execu\u00e7\u00e3o, bem como presta\u00e7\u00e3o de contas. Lei Rouanet, Leis de incentivo ao Esporte, \u00e0 Cultura, Editais, Chamamentos P\u00fablicos e Projetos para Emendas parlamentares.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/organizacao-de-eventos\/\">Veja Aqui<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slider-image\" >\n\t\t\t\t\t\t\t<img width=\"1920\" height=\"700\"\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/banner-principal1.jpg\"\n\t\t\t\t\t\t\t\t\talt=\"Gest\u00e3o de M\u00eddias Sociais\"\n\t\t\t\t\t\t\t\t\ttitle=\"Gest\u00e3o de M\u00eddias Sociais\"\/>\n\t\t\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slider-content\">\n\t\t\t\t\t\t\t<div class=\"tg-container\">\n\t\t\t\t\t\t\t\t<div class=\"caption-title\">Gest\u00e3o de M\u00eddias Sociais<\/div>\n\t\t\t\t\t\t\t\t<div class=\"caption-desc\">As Redes Sociais s\u00e3o as mais eficientes ferramentas de comunica\u00e7\u00e3o da atualidade e se fazem fundamentais para o bom relacionamento da empresa com seus clientes, potenciais clientes, colaboradores e o mercado em geral.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/midias-sociais\/\">Conhe\u00e7a Mais<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slider-image\" >\n\t\t\t\t\t\t\t<img width=\"1920\" height=\"701\"\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/banner-principal2.jpg\"\n\t\t\t\t\t\t\t\t\talt=\"Assessoria de Imprensa\"\n\t\t\t\t\t\t\t\t\ttitle=\"Assessoria de Imprensa\"\/>\n\t\t\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slider-content\">\n\t\t\t\t\t\t\t<div class=\"tg-container\">\n\t\t\t\t\t\t\t\t<div class=\"caption-title\">Assessoria de Imprensa<\/div>\n\t\t\t\t\t\t\t\t<div class=\"caption-desc\">A boa rela\u00e7\u00e3o com os meios de comunica\u00e7\u00e3o, sejam impressos, audiovisuais ou online, mant\u00ea-los atualizados sobre as atividades da empresa e ter visibilidade na imprensa s\u00e3o indispens\u00e1veis a\u00e7\u00f5es para organiza\u00e7\u00f5es que buscam o sucesso.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/assessoria-imprensa\/\">Saiba mais<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slider-image\" >\n\t\t\t\t\t\t\t<img width=\"1920\" height=\"700\"\t\t\t\t\t\t\t\t\tsrc=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/banner-principal3.jpg\"\n\t\t\t\t\t\t\t\t\talt=\"Desenvolvimento de Sites e E-Commerce\"\n\t\t\t\t\t\t\t\t\ttitle=\"Desenvolvimento de Sites e E-Commerce\"\/>\n\t\t\t\t\t\t\t<div class=\"overlay\"><\/div>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slider-content\">\n\t\t\t\t\t\t\t<div class=\"tg-container\">\n\t\t\t\t\t\t\t\t<div class=\"caption-title\">Desenvolvimento de Sites e E-Commerce<\/div>\n\t\t\t\t\t\t\t\t<div class=\"caption-desc\">Estar na internet \u00e9 hoje obrigat\u00f3rio para empresas, ONGs e profissionais liberais que buscam atingir seus objetivos. Ter um site din\u00e2mico, intuitivo e coerente com seus servi\u00e7os faz a diferen\u00e7a, seja de forma institucional ou para realizar vendas e servi\u00e7os online.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/desenvolvimento-de-sites\/\">Leia Mais<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t<div class=\"slider-arrow\">\n\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-643-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-643-1\" ><div id=\"pgc-643-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-1-0-0\" class=\"so-panel widget widget_themegrill_flash_heading tg-widget section-title-wrapper panel-first-child\" data-index=\"1\" >\t<h3 class=\"section-title\">SERVI\u00c7OS<\/h3>\n\t<div class=\"section-description\">Encontre aqui tudo para desenvolver e implantar produtos e servi\u00e7os de comunica\u00e7\u00e3o, visando a satisfa\u00e7\u00e3o e o sucesso de seus clientes, alinhando tend\u00eancias \u00e0s necessidades e contribuindo para uma maior visibilidade das institui\u00e7\u00f5es e profissionais liberais.<\/div>\n<\/div><div id=\"panel-643-1-0-1\" class=\"so-panel widget widget_themegrill_flash_portfolio tg-section feature-product-section panel-last-child\" data-index=\"2\" ><div class=\"tg-feature-product-layout-1 tg-feature-product-filter-layout\"><div class=\"tg-container\"><div class=\"grid\"><div class=\"tg-column-wrapper\"><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-redes2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-redes2.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-redes2-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-redes2-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-redes2-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/midias-sociais\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/midias-sociais\/\">Gest\u00e3o de M\u00eddias Sociais<\/a><\/h3><h4 class=\"feature-desc-wrap\">Nos dias atuais, uma empresa n\u00e3o se comunica sem Redes Sociais. P\u00e1ginas profissionais e perfis corporativos s\u00e3o, hoje, os maiores [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-imprensa2.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-imprensa2.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-imprensa2-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-imprensa2-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-imprensa2-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/assessoria-imprensa\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/assessoria-imprensa\/\">Assessoria de Imprensa<\/a><\/h3><h4 class=\"feature-desc-wrap\">Ter visibilidade na imprensa e mander os jornalistas atualizados sobre o o que acontece na empresa s\u00e3o a\u00e7\u00f5es indispens\u00e1veis para [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-politica.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-politica.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-politica-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-politica-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-assessoria-politica-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/assessoria-politica\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/assessoria-politica\/\">Assessoria Pol\u00edtica<\/a><\/h3><h4 class=\"feature-desc-wrap\">Qualquer candidato ou pol\u00edtico eleito necessita de uma eficiente assessoria para cuidar de sua imagem, de seus discursos e, em [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-relacoes-publicas.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-relacoes-publicas.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-relacoes-publicas-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-relacoes-publicas-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-relacoes-publicas-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/relacoes-publicas\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/relacoes-publicas\/\">Rela\u00e7\u00f5es P\u00fablicas<\/a><\/h3><h4 class=\"feature-desc-wrap\">A Eh! Comunica\u00e7\u00e3o &#038; Projetos promove comunica\u00e7\u00e3o e relacionamento entre seus clientes e diversos p\u00fablicos, como funcion\u00e1rios, consumidores de produtos [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-desenvolvimento-site.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-desenvolvimento-site.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-desenvolvimento-site-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-desenvolvimento-site-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-desenvolvimento-site-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/desenvolvimento-de-sites\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/desenvolvimento-de-sites\/\">Desenvolvimento de Sites e Apps<\/a><\/h3><h4 class=\"feature-desc-wrap\">Estar na internet \u00e9 hoje obrigat\u00f3rio para empresas, ONGs e profissionais liberais que buscam atingir seus objetivos. Sua interatividade permite [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-eventos.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-eventos.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-eventos-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-eventos-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-eventos-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/organizacao-de-eventos\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/organizacao-de-eventos\/\">Elabora\u00e7\u00e3o e Gest\u00e3o de Projetos e Eventos<\/a><\/h3><h4 class=\"feature-desc-wrap\">ELABORA\u00c7\u00c3O DE PROJETOS Empresas e pessoas f\u00edsicas que pensam em tirar projetos do campo das ideias e fazer acontecer, precisam [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-sites.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-sites.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-sites-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-sites-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-sites-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/edicao\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/edicao\/\">Edi\u00e7\u00e3o de Revistas, jornais e livros<\/a><\/h3><h4 class=\"feature-desc-wrap\">A Eh! Comunica\u00e7\u00e3o tem vasta experi\u00eancia na edi\u00e7\u00e3o de impressos, sempre priorizando a personalidade do cliente, a modernidade e, principalmente, [&hellip;]<\/h4><\/div><\/div><\/div><div class=\"tg-feature-product-widget element-item uxdesign tg-column-4 servicos \" data-category=\"servicos \"><figure><img loading=\"lazy\" decoding=\"async\" width=\"401\" height=\"401\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-publicidade.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-publicidade.jpg 401w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-publicidade-300x300.jpg 300w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-publicidade-150x150.jpg 150w, https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/servicos-publicidade-100x100.jpg 100w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure><div class=\"featured-image-desc\"><span><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/publicidade-e-propaganda\/\"><i class=\"fa fa-plus\"><\/i><\/a><\/span><div class=\"feature-inner-block\"><h3 class=\"feature-title-wrap\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/publicidade-e-propaganda\/\">Publicidade, Propaganda e Marketing<\/a><\/h3><h4 class=\"feature-desc-wrap\">Realizamos o planejamento, a cria\u00e7\u00e3o e a divulga\u00e7\u00e3o de campanhas de propaganda, pe\u00e7as publicit\u00e1rias e todo sistema de marketing para [&hellip;]<\/h4><\/div><\/div><\/div><\/div><!-- \/.tg-column-wrapper--><\/div><!-- \/.grid --><\/div><!-- \/.tg-container --><\/div><!-- \/.layout div --><\/div><\/div><\/div><\/div><div id=\"pg-643-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-643-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-2-0-0\" class=\"so-panel widget widget_themegrill_flash_service tg-widget tg-single-service panel-first-child panel-last-child\" data-index=\"3\" >\n<div class=\"tg-service-widget tg-service-layout-1\">\n\t<div class=\"service-wrapper\">\n\t\t<div class=\"service-icon-title-wrapper clearfix\">\n\t\t\t\t\t\t<div class=\"service-icon-wrap\"><i class=\"fa fa-whatsapp\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"service-title-wrap\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/administracao-de-whatsapp\/\">\n\t\t\t\tADMINISTRA\u00c7\u00c3O DE WHATSAPP\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"service-content-wrap\">Um contato direto com seu p\u00fablico em atendimento personalizado, al\u00e9m de uma ferramenta de informa\u00e7\u00e3o direta e instant\u00e2nea de seus conte\u00fados para um p\u00fablico espec\u00edfico. Responder de forma pessoal a seus clientes \u00e9 o grande diferencial do mundo corporativo na atualidade.<\/div>\n\t\t\t\t\t\t<a class=\"service-more\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/administracao-de-whatsapp\/\">CONHE\u00c7A MAIS<\/a>\n\t\t\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-2-1\"  class=\"panel-grid-cell\" ><div id=\"panel-643-2-1-0\" class=\"so-panel widget widget_themegrill_flash_service tg-widget tg-single-service panel-first-child panel-last-child\" data-index=\"4\" >\n<div class=\"tg-service-widget tg-service-layout-1\">\n\t<div class=\"service-wrapper\">\n\t\t<div class=\"service-icon-title-wrapper clearfix\">\n\t\t\t\t\t\t<div class=\"service-icon-wrap\"><i class=\"fa fa-commenting\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"service-title-wrap\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/digital-influencer-menager\/\">\n\t\t\t\tDIGITAL INFLUENCER\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"service-content-wrap\">Voc\u00ea ou sua empresa podem se tornar um influenciador digital e propagar servi\u00e7os ou produtos para um p\u00fablico maior e mais fidelizado. Este servi\u00e7o administra p\u00e1ginas online, redes sociais e canais para a proje\u00e7\u00e3o de conte\u00fados.<\/div>\n\t\t\t\t\t\t<a class=\"service-more\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/digital-influencer-menager\/\">SAIBA MAIS<\/a>\n\t\t\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-2-2\"  class=\"panel-grid-cell\" ><div id=\"panel-643-2-2-0\" class=\"so-panel widget widget_themegrill_flash_service tg-widget tg-single-service panel-first-child panel-last-child\" data-index=\"5\" >\n<div class=\"tg-service-widget tg-service-layout-1\">\n\t<div class=\"service-wrapper\">\n\t\t<div class=\"service-icon-title-wrapper clearfix\">\n\t\t\t\t\t\t<div class=\"service-icon-wrap\"><i class=\"fa fa-group\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"service-title-wrap\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/endomarketing\/\">\n\t\t\t\tENDOMARKETING\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"service-content-wrap\">A propaganda da sua empresa come\u00e7a de dentro para fora. O primeiro passo para a forma\u00e7\u00e3o de uma imagem favor\u00e1vel de uma empresa \u00e9 conquistar a simpatia dos seus empregados, que poder\u00e3o se transformar em verdadeiros aliados no crescimento e no sucesso da institui\u00e7\u00e3o.<\/div>\n\t\t\t\t\t\t<a class=\"service-more\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/portfolio\/endomarketing\/\">LEIA MAIS<\/a>\n\t\t\t<\/div>\n<\/div>\n<\/div><\/div><\/div><div id=\"pg-643-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-643-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-3-0-0\" class=\"so-panel widget widget_themegrill_flash_heading tg-widget section-title-wrapper panel-first-child panel-last-child\" data-index=\"6\" >\t<h3 class=\"section-title\">Portfolio<\/h3>\n<\/div><\/div><\/div><div id=\"pg-643-4\"  class=\"panel-grid panel-has-style panel-has-overlay\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-643-4\" data-stretch-type=\"full\" >\t\t\t\t<div\n\t\t\t\t\tclass=\"panel-background-overlay\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"background-color:#262626;opacity:0.54;\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"pgc-643-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-4-0-0\" class=\"so-panel widget widget_themegrill_flash_counter tg-widget tg-single-counter panel-first-child panel-last-child\" data-index=\"7\" ><div class=\"fun-facts-section\">\n\t<div class=\"tg-fun-facts-widget tg-fun-facts-layout-1\">\n\t\t<div class=\"fun-facts-wrapper\">\n\t\t\t\t\t\t<span class=\"fun-facts-icon-wrap\"><i class=\"fa fa-handshake-o\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"counter-wrapper\"><span class=\"counter\">250<\/span><i class=\"fa fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"fun-facts-title-wrap\">Clientes Atendidos<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-4-1\"  class=\"panel-grid-cell\" ><div id=\"panel-643-4-1-0\" class=\"so-panel widget widget_themegrill_flash_counter tg-widget tg-single-counter panel-first-child panel-last-child\" data-index=\"8\" ><div class=\"fun-facts-section\">\n\t<div class=\"tg-fun-facts-widget tg-fun-facts-layout-1\">\n\t\t<div class=\"fun-facts-wrapper\">\n\t\t\t\t\t\t<span class=\"fun-facts-icon-wrap\"><i class=\"fa fa-cubes\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"counter-wrapper\"><span class=\"counter\">30<\/span><i class=\"fa fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"fun-facts-title-wrap\">Projetos Desenvolvidos<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-4-2\"  class=\"panel-grid-cell\" ><div id=\"panel-643-4-2-0\" class=\"so-panel widget widget_themegrill_flash_counter tg-widget tg-single-counter panel-first-child panel-last-child\" data-index=\"9\" ><div class=\"fun-facts-section\">\n\t<div class=\"tg-fun-facts-widget tg-fun-facts-layout-1\">\n\t\t<div class=\"fun-facts-wrapper\">\n\t\t\t\t\t\t<span class=\"fun-facts-icon-wrap\"><i class=\"fa fa-tachometer\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"counter-wrapper\"><span class=\"counter\">2340<\/span><i class=\"fa fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"fun-facts-title-wrap\">Trabalhos Executados<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-4-3\"  class=\"panel-grid-cell\" ><div id=\"panel-643-4-3-0\" class=\"so-panel widget widget_themegrill_flash_counter tg-widget tg-single-counter panel-first-child panel-last-child\" data-index=\"10\" ><div class=\"fun-facts-section\">\n\t<div class=\"tg-fun-facts-widget tg-fun-facts-layout-1\">\n\t\t<div class=\"fun-facts-wrapper\">\n\t\t\t\t\t\t<span class=\"fun-facts-icon-wrap\"><i class=\"fa fa-internet-explorer\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"counter-wrapper\"><span class=\"counter\">110<\/span><i class=\"fa fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t<h3 class=\"fun-facts-title-wrap\">Sites Criados<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-643-5\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-643-5\" ><div id=\"pgc-643-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-5-0-0\" class=\"so-panel widget widget_themegrill_flash_heading tg-widget section-title-wrapper panel-first-child\" data-index=\"11\" >\t<h3 class=\"section-title\">Releases Produzidos<\/h3>\n\t<div class=\"section-description\">Confira todas as not\u00edcias, internas ou de clientes, produzidas pela Eh! Comunica\u00e7\u00e3o &amp; Projetos<\/div>\n<\/div><div id=\"panel-643-5-0-1\" class=\"so-panel widget widget_themegrill_flash_blog tg-widget blog-section panel-last-child\" data-index=\"12\" >\n<div class=\"blog-wrapper tg-column-wrapper tg-blog-widget-layout-2\">\n\t\t<div class=\"tg-blog-widget tg-column-3\">\n\t\t\t\t<div class=\"post-image \">\n\t\t\t<figure><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2023\/01\/30\/casa-de-portugal-sedia-ciclo-de-palestras\/\" title=\"Casa de Portugal de Petr\u00f3polis sedia Ciclo de Palestras para profissionais\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"270\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-30-at-11.24.56-370x270.jpeg\" class=\"attachment-flash-grid size-flash-grid wp-post-image\" alt=\"\" \/><\/a><\/figure>\t\t\t<span class=\"entry-date\">\n\t\t\t\t<i class=\"fa fa-clock-o\"><\/i><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2023\/01\/30\/casa-de-portugal-sedia-ciclo-de-palestras\/\" rel=\"bookmark\">30 de janeiro de 2023<\/a>\n\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"blog-content\">\n\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2023\/01\/30\/casa-de-portugal-sedia-ciclo-de-palestras\/\">Casa de Portugal de Petr\u00f3polis sedia Ciclo de Palestras para profissionais<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-summary\">\n\t\t\t\t<p>Nos dias 11 e 12 de fevereiro, a Casa de Portugal de Petr\u00f3polis ir\u00e1 sediar o ciclo de palestras \u201cNa Trilha do Sucesso\u201d. O evento, que j\u00e1 teve edi\u00e7\u00f5es em v\u00e1rias cidades do pa\u00eds, com o intuito de ajudar a desenvolver as regi\u00f5es do Brasil e mudar o rumo dos neg\u00f3cios e da vida de profissionais e empreendedores. De acordo com a programa\u00e7\u00e3o do evento, ser\u00e3o 22 temas abordados por diversos palestrantes, de m\u00faltiplas especialidades.<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"read-more-container\">\n\t\t\t\t<span class=\"entry-author\">\n\t\t\t\t\t<i class=\"fa fa-user\"><\/i><a class=\"url fn n\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/author\/ehcomunicacao\/\">ehcomunicacao<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t<div class=\"read-more\">\n\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2023\/01\/30\/casa-de-portugal-sedia-ciclo-de-palestras\/\">Read More<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"tg-blog-widget tg-column-3\">\n\t\t\t\t<div class=\"post-image \">\n\t\t\t<figure><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/26\/photography-tips-for-photographer\/\" title=\"Eh! lan\u00e7a novo site e mais servi\u00e7os\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"270\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2017\/01\/noticia-3-370x270.jpg\" class=\"attachment-flash-grid size-flash-grid wp-post-image\" alt=\"\" \/><\/a><\/figure>\t\t\t<span class=\"entry-date\">\n\t\t\t\t<i class=\"fa fa-clock-o\"><\/i><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/26\/photography-tips-for-photographer\/\" rel=\"bookmark\">26 de dezembro de 2022<\/a>\n\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"blog-content\">\n\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/26\/photography-tips-for-photographer\/\">Eh! lan\u00e7a novo site e mais servi\u00e7os<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-summary\">\n\t\t\t\t<p>Caminhando para os seus 16 anos de exist\u00eancia no mercado da comunica\u00e7\u00e3o de Petr\u00f3polis e regi\u00e3o, a Eh! Comunica\u00e7\u00e3o &amp; Projetos atualizou todo seu projeto visual para o ano de 2023. Agora, a empresa assumiu novo dom\u00ednio e lan\u00e7ou um site mais moderno e completo, com detalhes sobre seus servi\u00e7os e, ainda not\u00edcias sobre seus projetos, releases e clientes e informa\u00e7\u00f5es internas. Al\u00e9m desse conte\u00fado, a Eh! tamb\u00e9m entra 2023 com novidades nos servi\u00e7os.<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"read-more-container\">\n\t\t\t\t<span class=\"entry-author\">\n\t\t\t\t\t<i class=\"fa fa-user\"><\/i><a class=\"url fn n\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/author\/ehcomunicacao\/\">ehcomunicacao<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t<div class=\"read-more\">\n\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/26\/photography-tips-for-photographer\/\">Read More<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"tg-blog-widget tg-column-3\">\n\t\t\t\t<div class=\"post-image \">\n\t\t\t<figure><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/20\/artistic-drawing-of-girl-has-gone-away\/\" title=\"Gilson Chveid Oen fala de 2023\"><img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"270\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/noticia-2-370x270.jpg\" class=\"attachment-flash-grid size-flash-grid wp-post-image\" alt=\"\" \/><\/a><\/figure>\t\t\t<span class=\"entry-date\">\n\t\t\t\t<i class=\"fa fa-clock-o\"><\/i><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/20\/artistic-drawing-of-girl-has-gone-away\/\" rel=\"bookmark\">20 de dezembro de 2022<\/a>\n\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"blog-content\">\n\t\t\t<h3 class=\"entry-title\"><a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/20\/artistic-drawing-of-girl-has-gone-away\/\">Gilson Chveid Oen fala de 2023<\/a><\/h3>\n\t\t\t\t\t\t<div class=\"entry-summary\">\n\t\t\t\t<p>O Engenheiro Gilson Chveid Oen, \u00e9 presen\u00e7a certa todos os anos no Programa Amaury Jr. Criador da Engenharia Dimensional, e considerado mundialmente por muitos o mais importante e respeitado Numer\u00f3logo Cient\u00edfico da atualidade, \u00e9 ele quem estuda e cria os Mantras, Temans e Praamzes para o ano que ir\u00e1 entrar. No \u00faltimo dia 15 de dezembro, ele esteve no programa da jornalista Leda Nagle, falando tudo sobre o ano de 2023 e como viver bem esse per\u00edodo.<\/p>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"read-more-container\">\n\t\t\t\t<span class=\"entry-author\">\n\t\t\t\t\t<i class=\"fa fa-user\"><\/i><a class=\"url fn n\" href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/author\/ehcomunicacao\/\">ehcomunicacao<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t<div class=\"read-more\">\n\t\t\t\t\t<a href=\"https:\/\/www.ehcomunicacao.com.br\/index.php\/2022\/12\/20\/artistic-drawing-of-girl-has-gone-away\/\">Read More<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<\/div><!-- .blog-wrapper -->\n<\/div><\/div><\/div><\/div><div id=\"pg-643-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-643-6\" data-stretch-type=\"full\" ><div id=\"pgc-643-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-6-0-0\" class=\"so-panel widget widget_themegrill_flash_cta tg-widget call-to-action-section panel-first-child panel-last-child\" data-index=\"13\" ><div class=\"panel-widget-style panel-widget-style-for-643-6-0-0\" ><div class=\"cta-wrapper call-to-action-section-layout-1\">\n\t<div class=\"section-title-wrapper\">\n\t\t\t\t<h3 class=\"section-title\">FA\u00c7A CONTATO E AGENDE UMA VISITA<\/h3>\n\t\t\t<\/div>\n\t\t<div class=\"btn-wrapper\">\n\t\t\t\t<a class=\"btn\" href=\"#\">Fale com a gente<\/a>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-643-7\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-643-7\" ><div id=\"pgc-643-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-7-0-0\" class=\"so-panel widget widget_themegrill_flash_heading tg-widget section-title-wrapper panel-first-child panel-last-child\" data-index=\"14\" >\t<h3 class=\"section-title\">NOSSOS CLIENTES<\/h3>\n\t<div class=\"section-description\">Clique e arraste para o lado para ver todos os clientes atualmente atendidos pela Eh! Comunica\u00e7\u00e3o<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-643-8\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-643-8-0\"  class=\"panel-grid-cell\" ><div id=\"panel-643-8-0-0\" class=\"so-panel widget widget_themegrill_flash_logo tg-section client-section panel-first-child panel-last-child\" data-index=\"15\" ><div class=\"tg-client-widget\">\n\t<div class=\"client-container swiper-container\">\n\t\t<div class=\"client-wrapper swiper-wrapper\">\n\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-cdl-e1671658129390.jpg\" alt=\"CDL Petr\u00f3polis\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-casa-carlos.jpg\" alt=\"Casa Carlos\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-casa-de-portugal.jpg\" alt=\"Casa de Portugal\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><div id=\"pgc-643-8-1\"  class=\"panel-grid-cell\" ><div id=\"panel-643-8-1-0\" class=\"so-panel widget widget_themegrill_flash_logo tg-section client-section panel-first-child panel-last-child\" data-index=\"16\" ><div class=\"tg-client-widget\">\n\t<div class=\"client-container swiper-container\">\n\t\t<div class=\"client-wrapper swiper-wrapper\">\n\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-talent.jpg\" alt=\"Talent Tour\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-gilson.jpg\" alt=\"Gilson Chveid Oen\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"client-slide swiper-slide\">\n\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.ehcomunicacao.com.br\/wp-content\/uploads\/2022\/12\/cliente-pronto.jpg\" alt=\"Pronto Brindes\" \/>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/pagebuilder.php","meta":{"footnotes":""},"class_list":["post-643","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/pages\/643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=643"}],"version-history":[{"count":116,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/pages\/643\/revisions"}],"predecessor-version":[{"id":1096,"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/pages\/643\/revisions\/1096"}],"wp:attachment":[{"href":"https:\/\/www.ehcomunicacao.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}